{"id":20016,"date":"2023-09-19T11:55:19","date_gmt":"2023-09-19T09:55:19","guid":{"rendered":"https:\/\/ggba.swiss\/ubs-boosts-swissto12s-aerospace-ambitions-with-chf-25-million-capital-injection\/"},"modified":"2023-09-19T11:58:24","modified_gmt":"2023-09-19T09:58:24","slug":"ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions","status":"publish","type":"post","link":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/","title":{"rendered":"UBS renforce les ambitions de SWISSto12 avec une injection de capital de CHF 25 millions"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/swissto12.com\/\">SWISSto12<\/a>, acteur majeur dans le paysage europ\u00e9en de production de satellites et de Radio Fr\u00e9quence, a r\u00e9cemment obtenu un renforcement de 25 millions de CHF en fonds de roulement de UBS Switzerland AG. Cette remarquable initiative financi\u00e8re est soutenue par SERV, l&rsquo;agence d\u00e9sign\u00e9e par le gouvernement suisse pour l&rsquo;assurance risque \u00e0 l&rsquo;export.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bas\u00e9e \u00e0 Lausanne, SWISSto12 s&rsquo;est distingu\u00e9e en tant que fabricant avant-gardiste de charges utiles pour satellites et de syst\u00e8mes. L&rsquo;une de ses inventions pionni\u00e8res, le HummingSat, se d\u00e9marque. Con\u00e7u en <a href=\"https:\/\/ggba.swiss\/fr\/swissto12-revolutionne-lindustrie-spatiale-europeenne-avec-sa-ligne-de-satellites-hummingsat\/\">partenariat avec l&rsquo;Agence Spatiale Europ\u00e9enne (ESA)<\/a>, HummingSat est un satellite de t\u00e9l\u00e9communication g\u00e9ostationnaire. Malgr\u00e9 sa taille compacte, il promet puissance et performance \u00e9quivalentes \u00e0 celles de ses homologues plus grands. Il convient de noter que des <a href=\"https:\/\/ggba.swiss\/fr\/swissto12-inaugure-une-nouvelle-ere-de-communications-par-satellite-avec-intelsat\/\">acteurs mondiaux tels qu&rsquo;Intelsat<\/a> et Inmarsat, r\u00e9cemment acquis par Viasat en 2023, figurent parmi ses principaux clients.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le CEO, Emile de Rijk, a d\u00e9taill\u00e9 l&rsquo;impact de la facilit\u00e9 de fonds de roulement : \u00ab&nbsp;Cette facilit\u00e9 de CHF 25 millions de l\u2019UBS nous offre une agilit\u00e9 suppl\u00e9mentaire pour la fabrication et la livraison de nos premiers HummingSats et pour r\u00e9pondre \u00e0 la forte demande des clients. Avec HummingSat, SWISSto12 cr\u00e9e une nouvelle cat\u00e9gorie de SmallSat agile et \u00e0 haute performance pour l&rsquo;orbite g\u00e9ostationnaire, qui est environ trois \u00e0 cinq fois plus petit et moins co\u00fbteux que les satellites g\u00e9ostationnaires conventionnels, tout en fournissant de mani\u00e8re fiable des services essentiels.&nbsp;\u00bb<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Red\u00e9finir l&rsquo;a\u00e9rospatiale avec une technologie 3D innovante<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le secret derri\u00e8re les satellites et les charges utiles de pointe de SWISSto12 r\u00e9side dans ses techniques propri\u00e9taires d&rsquo;impression 3D et ses conceptions de ses produits RF. Ces technologies aboutissent \u00e0 une fonctionnalit\u00e9 RF l\u00e9g\u00e8re, compacte et performante. Mais leur prouesse ne se limite pas \u00e0 l\u2019a\u00e9rospatial. SWISSto12 a \u00e9galement fait sensation dans l&rsquo;industrie a\u00e9ronautique, proposant des produits pour les t\u00e9l\u00e9communications, la surveillance et les applications radar. La solide croissance commerciale de l&rsquo;entreprise l&rsquo;a fait conna\u00eetre dans des r\u00e9gions telles que l&rsquo;Europe, les \u00c9tats-Unis et Isra\u00ebl, en faisant l&rsquo;une des entreprises a\u00e9rospatiales \u00e0 la croissance la plus rapide sur le continent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00e4r Lange, de Swisscom Ventures et investisseur chez SWISSto12, a partag\u00e9 ce sentiment, d\u00e9clarant : \u00ab&nbsp;SWISSto12 est la premi\u00e8re entreprise en phase de croissance \u00e0 vendre un satellite g\u00e9ostationnaire entier \u00e0 des op\u00e9rateurs de satellites mondiaux &#8211; un t\u00e9moignage du potentiel de march\u00e9 unique et transformateur de la plateforme HummingSat et de l&rsquo;acuit\u00e9 technique et commerciale de l&rsquo;\u00e9quipe. Ayant g\u00e9n\u00e9r\u00e9 plus de EUR 200 millions de commandes clients, SWISSto12 est \u00e9galement l&rsquo;une des rares entreprises en phase de croissance \u00e0 obtenir une facilit\u00e9 de croissance de cette ampleur d&rsquo;une banque multinationale telle que l\u2019UBS &#8211; l&rsquo;entreprise est dans une position extr\u00eamement favorable pour revitaliser le march\u00e9 des communications g\u00e9ostationnaires sur lequel des milliards de personnes comptent pour les services de haut d\u00e9bit, de diffusion et de s\u00e9curit\u00e9.&nbsp;\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9put\u00e9e pour ses produits satellites avanc\u00e9s et de Radio Fr\u00e9quence (RF), l\u2019entreprise vaudoise SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.<\/p>\n","protected":false},"author":6,"featured_media":20012,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[845],"tags":[1187,1148,1153,1189],"class_list":["post-20016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech","tag-aerospace-fr-2","tag-financing-fr-2","tag-ict-fr","tag-space-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHF 25 millions pour booster les ambitions a\u00e9rospatiales de SWISSto12<\/title>\n<meta name=\"description\" content=\"SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHF 25 millions pour booster les ambitions a\u00e9rospatiales de SWISSto12\" \/>\n<meta property=\"og:description\" content=\"SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\" \/>\n<meta property=\"og:site_name\" content=\"Greater Geneva Bern area\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-19T09:55:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-19T09:58:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1180\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre-Yves Oehrli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Yves Oehrli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\"},\"author\":{\"name\":\"Pierre-Yves Oehrli\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"headline\":\"UBS renforce les ambitions de SWISSto12 avec une injection de capital de CHF 25 millions\",\"datePublished\":\"2023-09-19T09:55:19+00:00\",\"dateModified\":\"2023-09-19T09:58:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\"},\"wordCount\":538,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg\",\"keywords\":[\"Aerospace\",\"Financing\",\"ICT\",\"Space\"],\"articleSection\":[\"Tech\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\",\"url\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\",\"name\":\"CHF 25 millions pour booster les ambitions a\u00e9rospatiales de SWISSto12\",\"isPartOf\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg\",\"datePublished\":\"2023-09-19T09:55:19+00:00\",\"dateModified\":\"2023-09-19T09:58:24+00:00\",\"author\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"description\":\"SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.\",\"breadcrumb\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage\",\"url\":\"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg\",\"contentUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg\",\"width\":1180,\"height\":811,\"caption\":\"S'appuyant sur ses succ\u00e8s pr\u00e9c\u00e9dents, tels que son partenariat avec l'ESA et le lancement r\u00e9volutionnaire de HummingSat, SWISSto12 affiche plus de EUR 200 millions de commandes clients, t\u00e9moignant de sa domination industrielle. | \u00a9 SWISSto12\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ggba.swiss\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UBS renforce les ambitions de SWISSto12 avec une injection de capital de CHF 25 millions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\",\"url\":\"https:\/\/staging.ggba.swiss\/en\/\",\"name\":\"Greater Geneva Bern area\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\",\"name\":\"Pierre-Yves Oehrli\",\"url\":\"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHF 25 millions pour booster les ambitions a\u00e9rospatiales de SWISSto12","description":"SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/","og_locale":"fr_FR","og_type":"article","og_title":"CHF 25 millions pour booster les ambitions a\u00e9rospatiales de SWISSto12","og_description":"SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.","og_url":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/","og_site_name":"Greater Geneva Bern area","article_published_time":"2023-09-19T09:55:19+00:00","article_modified_time":"2023-09-19T09:58:24+00:00","og_image":[{"width":1180,"height":811,"url":"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg","type":"image\/jpeg"}],"author":"Pierre-Yves Oehrli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre-Yves Oehrli","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#article","isPartOf":{"@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/"},"author":{"name":"Pierre-Yves Oehrli","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"headline":"UBS renforce les ambitions de SWISSto12 avec une injection de capital de CHF 25 millions","datePublished":"2023-09-19T09:55:19+00:00","dateModified":"2023-09-19T09:58:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/"},"wordCount":538,"commentCount":0,"image":{"@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg","keywords":["Aerospace","Financing","ICT","Space"],"articleSection":["Tech"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/","url":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/","name":"CHF 25 millions pour booster les ambitions a\u00e9rospatiales de SWISSto12","isPartOf":{"@id":"https:\/\/staging.ggba.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage"},"image":{"@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg","datePublished":"2023-09-19T09:55:19+00:00","dateModified":"2023-09-19T09:58:24+00:00","author":{"@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"description":"SWISSto12 a r\u00e9cemment fait les gros titres en s\u00e9curisant un important fonds de roulement de CHF 25 millionsUBS Switzerland AG.","breadcrumb":{"@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#primaryimage","url":"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg","contentUrl":"https:\/\/ggba.swiss\/app\/uploads\/2023\/09\/Swissto12-HummingSat-1180x811-1.jpg","width":1180,"height":811,"caption":"S'appuyant sur ses succ\u00e8s pr\u00e9c\u00e9dents, tels que son partenariat avec l'ESA et le lancement r\u00e9volutionnaire de HummingSat, SWISSto12 affiche plus de EUR 200 millions de commandes clients, t\u00e9moignant de sa domination industrielle. | \u00a9 SWISSto12"},{"@type":"BreadcrumbList","@id":"https:\/\/ggba.swiss\/fr\/ubs-renforce-les-ambitions-de-swissto12-avec-une-injection-de-capital-de-chf-25-millions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ggba.swiss\/fr\/"},{"@type":"ListItem","position":2,"name":"UBS renforce les ambitions de SWISSto12 avec une injection de capital de CHF 25 millions"}]},{"@type":"WebSite","@id":"https:\/\/staging.ggba.swiss\/en\/#website","url":"https:\/\/staging.ggba.swiss\/en\/","name":"Greater Geneva Bern area","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41","name":"Pierre-Yves Oehrli","url":"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/"}]}},"_links":{"self":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/20016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/comments?post=20016"}],"version-history":[{"count":1,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/20016\/revisions"}],"predecessor-version":[{"id":20018,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/20016\/revisions\/20018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media\/20012"}],"wp:attachment":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media?parent=20016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/categories?post=20016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/tags?post=20016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}