{"id":22076,"date":"2024-01-22T10:04:29","date_gmt":"2024-01-22T09:04:29","guid":{"rendered":"https:\/\/ggba.swiss\/stalicla-secures-usd-17-4-million-to-propel-neuro-precision-medicine\/"},"modified":"2024-01-22T10:10:14","modified_gmt":"2024-01-22T09:10:14","slug":"stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie","status":"publish","type":"post","link":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/","title":{"rendered":"STALICLA l\u00e8ve USD 17,4 millions pour faire avancer la m\u00e9decine de pr\u00e9cision en neurologie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bas\u00e9e au <a href=\"https:\/\/www.campusbiotech.ch\/\">Campus Biotech<\/a> \u00e0 Gen\u00e8ve, <a href=\"https:\/\/stalicla.com\/\">STALICLA<\/a> est une soci\u00e9t\u00e9 de neurosciences mol\u00e9culaires de pr\u00e9cision en phase clinique. Elle d\u00e9veloppe, par le biais de sa plateforme DEPI de neurologie de pr\u00e9cision, deux actifs dans le domaine de l&rsquo;autisme de pr\u00e9cision : STP1 et STP2. Suite \u00e0 <a href=\"https:\/\/ggba.swiss\/fr\/la-start-up-genevoise-stalicla-signe-un-accord-de-licence-exclusif-avec-novartis\/\">l&rsquo;obtention d&rsquo;une licence de Novartis pour son produit mavoglurant en 2023<\/a>, STALICLA a \u00e9galement mis en place une plateforme NAM mGLuR5 avanc\u00e9e, annon\u00e7ant une nouvelle \u00e8re dans les possibilit\u00e9s de traitement en neurologie et en neuropsychiatrie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En janvier 2024, la soci\u00e9t\u00e9 a cl\u00f4tur\u00e9 avec succ\u00e8s son premier tour de financement de s\u00e9rie B, r\u00e9unissant USD 17,4 millions. Ce tour de table a \u00e9t\u00e9 men\u00e9 par SPRIM Global Investments Pte, Ltd, et a b\u00e9n\u00e9fici\u00e9 de contributions substantielles de la part des principaux investisseurs, y compris une facilit\u00e9 de cr\u00e9dit de USD 3,8 millions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet afflux de fonds est destin\u00e9 \u00e0 plusieurs initiatives essentielles. En premier lieu, il soutiendra la pr\u00e9paration de l&rsquo;essai de pr\u00e9cision de phase 2 de STALICLA sur les troubles du spectre autistique (TSA) &#8211; STP1. En outre, il permettra la mise en place de sa plateforme STP7 de modulateur allost\u00e9rique n\u00e9gatif du mGluR5 (mGluR5 NAM). Cela inclut le lancement d&rsquo;une \u00e9tude de phase III sur les troubles li\u00e9s \u00e0 l&rsquo;utilisation de substances, pr\u00e9vue pour 2025 et enti\u00e8rement soutenue par le NIH\/National Institute on Drug Abuse (Institut national sur l&rsquo;abus de drogues). En outre, les fonds soutiendront l&rsquo;essai en cours de biosampling\/identification des patients STA-B-001, qui recrute actuellement des participants aux \u00c9tats-Unis, en Espagne et en Australie. STALICLA pr\u00e9voit \u00e9galement d&rsquo;am\u00e9liorer l&rsquo;ensemble des mesures de soutien pour son deuxi\u00e8me produit de pr\u00e9cision sur les TSA, STP2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lynn Durham, CEO de STALICLA, s&rsquo;est montr\u00e9e enthousiaste face \u00e0 ce d\u00e9veloppement : \u00ab\u00a0Ce soutien financier souligne le r\u00f4le de pionnier de STALICLA dans le domaine de la neuropr\u00e9cision, avec des applications initiales en psychiatrie de pr\u00e9cision. De plus, notre plateforme STP7 mGluR5 NAM offre de multiples opportunit\u00e9s de d\u00e9veloppement clinique avanc\u00e9 dans le domaine de la neurologie au sens large, \u00e0 un moment o\u00f9 les progr\u00e8s cliniques r\u00e9cents et l&rsquo;augmentation du niveau d&rsquo;activit\u00e9 des transactions dans le domaine de la neurologie et de la neuropsychiatrie arrivent \u00e0 point nomm\u00e9. Il n&rsquo;y a jamais eu de p\u00e9riode plus prometteuse pour faire avancer les options th\u00e9rapeutiques transformatrices pour des millions de patients atteints de maladies c\u00e9r\u00e9brales et STALICLA est d\u00e9termin\u00e9e \u00e0 jouer un r\u00f4le cl\u00e9 dans ces progr\u00e8s.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au vu de ces avanc\u00e9es, STALICLA renforcera son \u00e9quipe de direction et son conseil d&rsquo;administration, posant ainsi des fondations solides pour ses projets futurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>STALICLA, une soci\u00e9t\u00e9 biopharmaceutique genevoise au stade clinique, a franchi une \u00e9tape importante dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.<\/p>\n","protected":false},"author":6,"featured_media":22072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[843],"tags":[1169,1148,1141,1171,1142],"class_list":["post-22076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sciences-de-la-vie","tag-biotech-fr-2","tag-financing-fr-2","tag-personalized-medicine-fr-2","tag-pharma-fr-2","tag-rd-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STALICLA fait avancer la m\u00e9decine de pr\u00e9cision en neurologie<\/title>\n<meta name=\"description\" content=\"STALICLA a fait un bond important dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STALICLA fait avancer la m\u00e9decine de pr\u00e9cision en neurologie\" \/>\n<meta property=\"og:description\" content=\"STALICLA a fait un bond important dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\" \/>\n<meta property=\"og:site_name\" content=\"Greater Geneva Bern area\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T09:04:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T09:10:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1-1024x704.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre-Yves Oehrli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Yves Oehrli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\"},\"author\":{\"name\":\"Pierre-Yves Oehrli\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"headline\":\"STALICLA l\u00e8ve USD 17,4 millions pour faire avancer la m\u00e9decine de pr\u00e9cision en neurologie\",\"datePublished\":\"2024-01-22T09:04:29+00:00\",\"dateModified\":\"2024-01-22T09:10:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\"},\"wordCount\":489,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg\",\"keywords\":[\"Biotech\",\"Financing\",\"Personalized Medicine\",\"Pharma\",\"R&amp;D\"],\"articleSection\":[\"Sciences de la vie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\",\"url\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\",\"name\":\"STALICLA fait avancer la m\u00e9decine de pr\u00e9cision en neurologie\",\"isPartOf\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg\",\"datePublished\":\"2024-01-22T09:04:29+00:00\",\"dateModified\":\"2024-01-22T09:10:14+00:00\",\"author\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"description\":\"STALICLA a fait un bond important dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.\",\"breadcrumb\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage\",\"url\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg\",\"contentUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg\",\"width\":2360,\"height\":1622,\"caption\":\"STALICLA a d\u00e9velopp\u00e9 la premi\u00e8re plateforme de m\u00e9decine de pr\u00e9cision sp\u00e9cifique aux troubles du d\u00e9veloppement neurologique, avec une premi\u00e8re application dans les troubles du spectre autistique (TSA).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ggba.swiss\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STALICLA l\u00e8ve USD 17,4 millions pour faire avancer la m\u00e9decine de pr\u00e9cision en neurologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\",\"url\":\"https:\/\/staging.ggba.swiss\/en\/\",\"name\":\"Greater Geneva Bern area\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\",\"name\":\"Pierre-Yves Oehrli\",\"url\":\"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STALICLA fait avancer la m\u00e9decine de pr\u00e9cision en neurologie","description":"STALICLA a fait un bond important dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/","og_locale":"fr_FR","og_type":"article","og_title":"STALICLA fait avancer la m\u00e9decine de pr\u00e9cision en neurologie","og_description":"STALICLA a fait un bond important dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.","og_url":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/","og_site_name":"Greater Geneva Bern area","article_published_time":"2024-01-22T09:04:29+00:00","article_modified_time":"2024-01-22T09:10:14+00:00","og_image":[{"width":1024,"height":704,"url":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1-1024x704.jpeg","type":"image\/jpeg"}],"author":"Pierre-Yves Oehrli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre-Yves Oehrli","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#article","isPartOf":{"@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/"},"author":{"name":"Pierre-Yves Oehrli","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"headline":"STALICLA l\u00e8ve USD 17,4 millions pour faire avancer la m\u00e9decine de pr\u00e9cision en neurologie","datePublished":"2024-01-22T09:04:29+00:00","dateModified":"2024-01-22T09:10:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/"},"wordCount":489,"commentCount":0,"image":{"@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg","keywords":["Biotech","Financing","Personalized Medicine","Pharma","R&amp;D"],"articleSection":["Sciences de la vie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/","url":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/","name":"STALICLA fait avancer la m\u00e9decine de pr\u00e9cision en neurologie","isPartOf":{"@id":"https:\/\/staging.ggba.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage"},"image":{"@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg","datePublished":"2024-01-22T09:04:29+00:00","dateModified":"2024-01-22T09:10:14+00:00","author":{"@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"description":"STALICLA a fait un bond important dans le d\u00e9veloppement de la m\u00e9decine de pr\u00e9cision pour les troubles neuropsychiatriques et neurologiques.","breadcrumb":{"@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#primaryimage","url":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg","contentUrl":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Stalicla-2360x1622-1.jpeg","width":2360,"height":1622,"caption":"STALICLA a d\u00e9velopp\u00e9 la premi\u00e8re plateforme de m\u00e9decine de pr\u00e9cision sp\u00e9cifique aux troubles du d\u00e9veloppement neurologique, avec une premi\u00e8re application dans les troubles du spectre autistique (TSA)."},{"@type":"BreadcrumbList","@id":"https:\/\/ggba.swiss\/fr\/stalicla-leve-usd-174-millions-pour-faire-avancer-la-medecine-de-precision-en-neurologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ggba.swiss\/fr\/"},{"@type":"ListItem","position":2,"name":"STALICLA l\u00e8ve USD 17,4 millions pour faire avancer la m\u00e9decine de pr\u00e9cision en neurologie"}]},{"@type":"WebSite","@id":"https:\/\/staging.ggba.swiss\/en\/#website","url":"https:\/\/staging.ggba.swiss\/en\/","name":"Greater Geneva Bern area","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41","name":"Pierre-Yves Oehrli","url":"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/"}]}},"_links":{"self":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/22076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/comments?post=22076"}],"version-history":[{"count":2,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/22076\/revisions"}],"predecessor-version":[{"id":22080,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/22076\/revisions\/22080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media\/22072"}],"wp:attachment":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media?parent=22076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/categories?post=22076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/tags?post=22076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}