{"id":22378,"date":"2024-03-13T08:00:00","date_gmt":"2024-03-13T07:00:00","guid":{"rendered":"https:\/\/ggba.swiss\/?p=22378"},"modified":"2024-03-13T14:25:45","modified_gmt":"2024-03-13T13:25:45","slug":"collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11","status":"publish","type":"post","link":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/","title":{"rendered":"Collaborations acad\u00e9miques et industrielles (Agri&amp;Food dans le canton de Fribourg 8\/11)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Collaborations acad\u00e9miques et industrielles&nbsp;\u00bb met en lumi\u00e8re les relations synergiques entre les institutions acad\u00e9miques et l&rsquo;industrie dans le secteur agroalimentaire fribourgeois. Un exemple embl\u00e9matique est JNJ Automation, leader mondial de la robotique fromag\u00e8re, d\u00e9velopp\u00e9 en collaboration avec l&rsquo;\u00e9cole d&rsquo;ing\u00e9nieurs de la Haute \u00e9cole sp\u00e9cialis\u00e9e de Fribourg. Ce champion cach\u00e9 incarne l&rsquo;int\u00e9gration de l&rsquo;agroalimentaire et de l&rsquo;industrie 4.0, en mettant en avant l&rsquo;automatisation avanc\u00e9e des processus de maturation du fromage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9pisode pr\u00e9sente \u00e9galement Neuria, une spin-off du d\u00e9partement de neurobiologie de l&rsquo;Universit\u00e9 de Fribourg. Elle a d\u00e9velopp\u00e9 une application de gamification qui promeut une alimentation saine, b\u00e9n\u00e9fique pour les personnes souffrant de diab\u00e8te ou d&rsquo;ob\u00e9sit\u00e9. Ces exemples illustrent la mani\u00e8re dont la technologie profonde et la science complexe issues de la recherche universitaire se traduisent par des applications pratiques et pr\u00eates \u00e0 \u00eatre commercialis\u00e9es, d\u00e9montrant ainsi l&rsquo;interaction puissante entre le monde universitaire et l&rsquo;industrie \u00e0 Fribourg.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Agri&amp;Food in the Canton of Fribourg - Academia Industry Collaborations (Part 8\/11)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/_juye7TmIwg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De l&rsquo;impact \u00e9conomique important et des strat\u00e9gies innovantes aux pratiques durables et aux efforts de collaboration qui fa\u00e7onnent l&rsquo;avenir de l&rsquo;agroalimentaire dans la r\u00e9gion, chaque \u00e9pisode de la <a href=\"https:\/\/www.youtube.com\/playlist?list=PLxu4sXGKajJJZsQRmUXtFKN_KRivTbmtY\">s\u00e9rie vid\u00e9o \u00ab&nbsp;Agri&amp;Food dans le canton de Fribourg&nbsp;\u00bb<\/a> fournit des informations uniques sur les raisons pour lesquelles le canton de Fribourg se transforme rapidement en un p\u00f4le majeur pour l&rsquo;innovation en mati\u00e8re d&rsquo;agroalimentaire et d&rsquo;agritech.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Agri&#038;Food dans le canton of Fribourg \u00bb est une s\u00e9rie vid\u00e9o en 11 parties qui se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.<\/p>\n","protected":false},"author":6,"featured_media":22192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[847],"tags":[1165,928,1166,1145,1139,1168],"class_list":["post-22378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agroalimentaire","tag-agritech-fr-2","tag-food-beverages","tag-food-beverages-fr-2","tag-foodtech-fr-2","tag-sustainability-fr-2","tag-technology-park-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collaborations acad\u00e9miques et industrielles (Agri&amp;Food Fribourg)<\/title>\n<meta name=\"description\" content=\"Cette s\u00e9rie de 11 vid\u00e9os se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collaborations acad\u00e9miques et industrielles (Agri&amp;Food Fribourg)\" \/>\n<meta property=\"og:description\" content=\"Cette s\u00e9rie de 11 vid\u00e9os se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Greater Geneva Bern area\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-13T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T13:25:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08-1024x704.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre-Yves Oehrli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Yves Oehrli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\"},\"author\":{\"name\":\"Pierre-Yves Oehrli\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"headline\":\"Collaborations acad\u00e9miques et industrielles (Agri&amp;Food dans le canton de Fribourg 8\/11)\",\"datePublished\":\"2024-03-13T07:00:00+00:00\",\"dateModified\":\"2024-03-13T13:25:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\"},\"wordCount\":279,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png\",\"keywords\":[\"Agritech\",\"Food &amp; Beverages\",\"Food &amp; Beverages\",\"FoodTech\",\"Sustainability\",\"Technology Park\"],\"articleSection\":[\"Agro-alimentaire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\",\"url\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\",\"name\":\"Collaborations acad\u00e9miques et industrielles (Agri&Food Fribourg)\",\"isPartOf\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png\",\"datePublished\":\"2024-03-13T07:00:00+00:00\",\"dateModified\":\"2024-03-13T13:25:45+00:00\",\"author\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"description\":\"Cette s\u00e9rie de 11 vid\u00e9os se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.\",\"breadcrumb\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage\",\"url\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png\",\"contentUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png\",\"width\":1180,\"height\":811,\"caption\":\"Pr\u00e9sent\u00e9e par Jerry Krattiger, directeur de la Promotion \u00e9conomique du canton de Fribourg, cette s\u00e9rie de vid\u00e9os offre une exploration approfondie des diverses facettes de l'industrie agroalimentaire du canton de Fribourg.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ggba.swiss\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collaborations acad\u00e9miques et industrielles (Agri&amp;Food dans le canton de Fribourg 8\/11)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\",\"url\":\"https:\/\/staging.ggba.swiss\/en\/\",\"name\":\"Greater Geneva Bern area\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\",\"name\":\"Pierre-Yves Oehrli\",\"url\":\"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collaborations acad\u00e9miques et industrielles (Agri&Food Fribourg)","description":"Cette s\u00e9rie de 11 vid\u00e9os se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/","og_locale":"fr_FR","og_type":"article","og_title":"Collaborations acad\u00e9miques et industrielles (Agri&Food Fribourg)","og_description":"Cette s\u00e9rie de 11 vid\u00e9os se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.","og_url":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/","og_site_name":"Greater Geneva Bern area","article_published_time":"2024-03-13T07:00:00+00:00","article_modified_time":"2024-03-13T13:25:45+00:00","og_image":[{"width":1024,"height":704,"url":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08-1024x704.png","type":"image\/png"}],"author":"Pierre-Yves Oehrli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre-Yves Oehrli","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#article","isPartOf":{"@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/"},"author":{"name":"Pierre-Yves Oehrli","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"headline":"Collaborations acad\u00e9miques et industrielles (Agri&amp;Food dans le canton de Fribourg 8\/11)","datePublished":"2024-03-13T07:00:00+00:00","dateModified":"2024-03-13T13:25:45+00:00","mainEntityOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/"},"wordCount":279,"commentCount":0,"image":{"@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png","keywords":["Agritech","Food &amp; Beverages","Food &amp; Beverages","FoodTech","Sustainability","Technology Park"],"articleSection":["Agro-alimentaire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/","url":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/","name":"Collaborations acad\u00e9miques et industrielles (Agri&Food Fribourg)","isPartOf":{"@id":"https:\/\/staging.ggba.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage"},"image":{"@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png","datePublished":"2024-03-13T07:00:00+00:00","dateModified":"2024-03-13T13:25:45+00:00","author":{"@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"description":"Cette s\u00e9rie de 11 vid\u00e9os se penche sur le secteur agroalimentaire dynamique et en pleine \u00e9volution du canton de Fribourg.","breadcrumb":{"@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#primaryimage","url":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png","contentUrl":"https:\/\/ggba.swiss\/app\/uploads\/2024\/01\/Fribourg-AgriFood-1180x811-08.png","width":1180,"height":811,"caption":"Pr\u00e9sent\u00e9e par Jerry Krattiger, directeur de la Promotion \u00e9conomique du canton de Fribourg, cette s\u00e9rie de vid\u00e9os offre une exploration approfondie des diverses facettes de l'industrie agroalimentaire du canton de Fribourg."},{"@type":"BreadcrumbList","@id":"https:\/\/ggba.swiss\/fr\/collaborations-academiques-et-industrielles-agrifood-dans-le-canton-de-fribourg-8-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ggba.swiss\/fr\/"},{"@type":"ListItem","position":2,"name":"Collaborations acad\u00e9miques et industrielles (Agri&amp;Food dans le canton de Fribourg 8\/11)"}]},{"@type":"WebSite","@id":"https:\/\/staging.ggba.swiss\/en\/#website","url":"https:\/\/staging.ggba.swiss\/en\/","name":"Greater Geneva Bern area","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41","name":"Pierre-Yves Oehrli","url":"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/"}]}},"_links":{"self":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/22378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/comments?post=22378"}],"version-history":[{"count":3,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/22378\/revisions"}],"predecessor-version":[{"id":23106,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/22378\/revisions\/23106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media\/22192"}],"wp:attachment":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media?parent=22378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/categories?post=22378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/tags?post=22378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}