{"id":30969,"date":"2025-02-10T11:18:18","date_gmt":"2025-02-10T10:18:18","guid":{"rendered":"https:\/\/ggba.swiss\/bern-based-cellntec-joins-neoliver-project-to-develop-bioprinted-liver-constructs\/"},"modified":"2025-02-10T11:21:31","modified_gmt":"2025-02-10T10:21:31","slug":"cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes","status":"publish","type":"post","link":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/","title":{"rendered":"CELLnTEC se joint au projet NEOLIVER pour d\u00e9velopper des mod\u00e8les de foie bio-imprim\u00e9s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/cellntec.com\/\">CELLnTEC<\/a> apporte son expertise en mati\u00e8re de culture cellulaire de pr\u00e9cision au projet<a href=\"https:\/\/neoliver.eu\/\"> NEOLIVER<\/a>, une initiative pionni\u00e8re dans le domaine de la m\u00e9decine r\u00e9g\u00e9n\u00e9rative. Soutenu par une bourse de EUR 10 millions d&rsquo;<a href=\"https:\/\/research-and-innovation.ec.europa.eu\/funding\/funding-opportunities\/funding-programmes-and-open-calls\/horizon-europe_en\">Horizon Europe<\/a> et du Secr\u00e9tariat d&rsquo;\u00c9tat \u00e0&nbsp;la formation, \u00e0&nbsp;la recherche et \u00e0 l&rsquo;innovation (<a href=\"https:\/\/www.sbfi.admin.ch\/sbfi\/fr\/home.html\">SEFRI<\/a>), NEOLIVER est dirig\u00e9 par l&rsquo;Universit\u00e9 d&rsquo;Utrecht et implique douze partenaires de recherche \u00e0 travers l&rsquo;Europe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les maladies du foie sont responsables de deux millions de d\u00e9c\u00e8s par an, et la p\u00e9nurie chronique d&rsquo;organes transplantables ne fait qu&rsquo;aggraver la crise. NEOLIVER vise \u00e0 offrir une alternative par la bio-impression de constructions h\u00e9patiques fonctionnelles \u00e0 l&rsquo;aide d&rsquo;organo\u00efdes d\u00e9riv\u00e9s de patients et de cellules de soutien, garantissant ainsi une option de traitement \u00e9volutive et personnalis\u00e9e. Le projet s&rsquo;appuie sur le succ\u00e8s d&rsquo;<a href=\"https:\/\/organtrans.eu\/\">ORGANTRANS<\/a>, une pr\u00e9c\u00e9dente initiative financ\u00e9e par l&rsquo;UE qui a permis la transplantation de petites constructions h\u00e9patiques chez la souris. NEOLIVER va plus loin en automatisant le processus de bioprinting et en d\u00e9veloppant des structures de tissus h\u00e9patiques plus grandes et cliniquement viables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CELLnTEC apporte \u00e0 NEOLIVER ses connaissances avanc\u00e9es en mati\u00e8re de milieux de pr\u00e9cision enti\u00e8rement d\u00e9finis, exempts de composants animaux et humains. L&rsquo;expertise de la soci\u00e9t\u00e9 est cruciale pour optimiser l&rsquo;expansion et la standardisation des cellules d\u00e9riv\u00e9es du patient, garantissant ainsi la qualit\u00e9 et la reproductibilit\u00e9 du tissu bioimprim\u00e9.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Faire avancer la bio-impression pour les applications cliniques<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">NEOLIVER int\u00e8gre de multiples technologies innovantes, dont le transfert direct induit par laser (LIFT) pour une structuration pr\u00e9cise des tissus, des strat\u00e9gies de vascularisation combinant des vaisseaux bioprints et des vaisseaux natifs de donneurs, et un syst\u00e8me de production automatis\u00e9 conforme aux BPF pour augmenter la production de tissus. Des essais pr\u00e9cliniques sur des porcs immunod\u00e9ficients permettront d&rsquo;\u00e9valuer l&rsquo;innocuit\u00e9 et l&rsquo;efficacit\u00e9 du produit, en vue de pr\u00e9parer les premiers essais sur l&rsquo;homme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le communiqu\u00e9 de presse de la soci\u00e9t\u00e9, le Dr Stefan B\u00e4rtschi, responsable de la R&amp;D chez CELLnTEC, a soulign\u00e9 le potentiel de transformation de NEOLIVER : \u00ab Nous sommes ravis d&rsquo;apporter notre expertise en mati\u00e8re de m\u00e9dias de pr\u00e9cision pour acc\u00e9l\u00e9rer l&rsquo;application clinique des constructions h\u00e9patiques bioprint\u00e9es. Ce projet nous rapproche de la solution \u00e0 la p\u00e9nurie mondiale d&rsquo;organes \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En combinant la biotechnologie, l&rsquo;automatisation et la m\u00e9decine, NEOLIVER repr\u00e9sente une avanc\u00e9e majeure dans le domaine de l&rsquo;ing\u00e9nierie tissulaire, en rapprochant de la r\u00e9alit\u00e9 des foies bio-imprim\u00e9s fonctionnels et transplantables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La biotech bernoise CELLnTEC jouera un r\u00f4le cl\u00e9 dans le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9 au monde destin\u00e9 \u00e0 un usage clinique. Ce projet, cofinanc\u00e9 par l&rsquo;UE et le gouvernement suisse, vise \u00e0 rem\u00e9dier \u00e0 la p\u00e9nurie mondiale de donneurs d&rsquo;organes gr\u00e2ce \u00e0 des technologies innovantes de bio-impression.<\/p>\n","protected":false},"author":6,"featured_media":30966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[843],"tags":[1186,1169,1188,1163,1142],"class_list":["post-30969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sciences-de-la-vie","tag-3d-printing-en-fr","tag-biotech-fr-2","tag-healthcare-fr-2","tag-medtech-fr-2","tag-rd-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La biotech bernoise CELLnTEC se joint au projet NEOLIVER<\/title>\n<meta name=\"description\" content=\"CELLnTEC rejoint le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La biotech bernoise CELLnTEC se joint au projet NEOLIVER\" \/>\n<meta property=\"og:description\" content=\"CELLnTEC rejoint le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\" \/>\n<meta property=\"og:site_name\" content=\"Greater Geneva Bern area\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T10:18:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T10:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1180\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre-Yves Oehrli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Yves Oehrli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\"},\"author\":{\"name\":\"Pierre-Yves Oehrli\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"headline\":\"CELLnTEC se joint au projet NEOLIVER pour d\u00e9velopper des mod\u00e8les de foie bio-imprim\u00e9s\",\"datePublished\":\"2025-02-10T10:18:18+00:00\",\"dateModified\":\"2025-02-10T10:21:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\"},\"wordCount\":473,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg\",\"keywords\":[\"3D Printing\",\"Biotech\",\"Healthcare\",\"Medtech\",\"R&amp;D\"],\"articleSection\":[\"Sciences de la vie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\",\"url\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\",\"name\":\"La biotech bernoise CELLnTEC se joint au projet NEOLIVER\",\"isPartOf\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg\",\"datePublished\":\"2025-02-10T10:18:18+00:00\",\"dateModified\":\"2025-02-10T10:21:31+00:00\",\"author\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"description\":\"CELLnTEC rejoint le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage\",\"url\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg\",\"contentUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg\",\"width\":1180,\"height\":811,\"caption\":\"CELLnTEC Advanced Cell Systems d\u00e9veloppe des technologies de culture cellulaire de pr\u00e9cision, permettant aux scientifiques du monde entier de cr\u00e9er des syst\u00e8mes cellulaires in vitro sophistiqu\u00e9s. | \u00a9 CELLnTEC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ggba.swiss\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CELLnTEC se joint au projet NEOLIVER pour d\u00e9velopper des mod\u00e8les de foie bio-imprim\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\",\"url\":\"https:\/\/staging.ggba.swiss\/en\/\",\"name\":\"Greater Geneva Bern area\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\",\"name\":\"Pierre-Yves Oehrli\",\"url\":\"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La biotech bernoise CELLnTEC se joint au projet NEOLIVER","description":"CELLnTEC rejoint le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/","og_locale":"fr_FR","og_type":"article","og_title":"La biotech bernoise CELLnTEC se joint au projet NEOLIVER","og_description":"CELLnTEC rejoint le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9.","og_url":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/","og_site_name":"Greater Geneva Bern area","article_published_time":"2025-02-10T10:18:18+00:00","article_modified_time":"2025-02-10T10:21:31+00:00","og_image":[{"width":1180,"height":811,"url":"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg","type":"image\/jpeg"}],"author":"Pierre-Yves Oehrli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre-Yves Oehrli","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#article","isPartOf":{"@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/"},"author":{"name":"Pierre-Yves Oehrli","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"headline":"CELLnTEC se joint au projet NEOLIVER pour d\u00e9velopper des mod\u00e8les de foie bio-imprim\u00e9s","datePublished":"2025-02-10T10:18:18+00:00","dateModified":"2025-02-10T10:21:31+00:00","mainEntityOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/"},"wordCount":473,"commentCount":0,"image":{"@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg","keywords":["3D Printing","Biotech","Healthcare","Medtech","R&amp;D"],"articleSection":["Sciences de la vie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/","url":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/","name":"La biotech bernoise CELLnTEC se joint au projet NEOLIVER","isPartOf":{"@id":"https:\/\/staging.ggba.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage"},"image":{"@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg","datePublished":"2025-02-10T10:18:18+00:00","dateModified":"2025-02-10T10:21:31+00:00","author":{"@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"description":"CELLnTEC rejoint le projet NEOLIVER, une initiative helv\u00e9tico-europ\u00e9enne qui vise \u00e0 d\u00e9velopper le premier foie autologue bio-imprim\u00e9.","breadcrumb":{"@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#primaryimage","url":"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg","contentUrl":"https:\/\/ggba.swiss\/app\/uploads\/2025\/02\/CELLntec-Bern-1180x811-1.jpg","width":1180,"height":811,"caption":"CELLnTEC Advanced Cell Systems d\u00e9veloppe des technologies de culture cellulaire de pr\u00e9cision, permettant aux scientifiques du monde entier de cr\u00e9er des syst\u00e8mes cellulaires in vitro sophistiqu\u00e9s. | \u00a9 CELLnTEC"},{"@type":"BreadcrumbList","@id":"https:\/\/ggba.swiss\/fr\/cellntec-se-joint-au-projet-neoliver-pour-developper-des-modeles-de-foie-bio-imprimes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ggba.swiss\/fr\/"},{"@type":"ListItem","position":2,"name":"CELLnTEC se joint au projet NEOLIVER pour d\u00e9velopper des mod\u00e8les de foie bio-imprim\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/staging.ggba.swiss\/en\/#website","url":"https:\/\/staging.ggba.swiss\/en\/","name":"Greater Geneva Bern area","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41","name":"Pierre-Yves Oehrli","url":"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/"}]}},"_links":{"self":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/30969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/comments?post=30969"}],"version-history":[{"count":1,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/30969\/revisions"}],"predecessor-version":[{"id":30971,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/30969\/revisions\/30971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media\/30966"}],"wp:attachment":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media?parent=30969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/categories?post=30969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/tags?post=30969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}