{"id":35927,"date":"2025-10-13T15:47:09","date_gmt":"2025-10-13T13:47:09","guid":{"rendered":"https:\/\/ggba.swiss\/ecorobotix-raises-usd-150-million-to-accelerate-ai-powered-precision-farming\/"},"modified":"2025-10-13T15:51:27","modified_gmt":"2025-10-13T13:51:27","slug":"ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia","status":"publish","type":"post","link":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/","title":{"rendered":"Ecorobotix l\u00e8ve USD 150 millions pour acc\u00e9l\u00e9rer l\u2019agriculture de pr\u00e9cision aliment\u00e9e par l\u2019IA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bas\u00e9e dans le canton de Vaud, <a href=\"https:\/\/ecorobotix.com\/\">Ecorobotix<\/a>, leader mondial de la pulv\u00e9risation ultra-haute pr\u00e9cision (UHP) assist\u00e9e par intelligence artificielle, a lev\u00e9 USD 150 millions pour \u00e9tendre sa technologie Plant-by-Plant et acc\u00e9l\u00e9rer sa croissance internationale. Ce montant combine les lev\u00e9es de fonds de S\u00e9rie C (USD 45 millions en 2024) et de S\u00e9rie D (USD 105 millions en 2025). Forte de son expansion rapide \u00e0 l\u2019international, l\u2019entreprise pr\u00e9sentera sa derni\u00e8re innovation lors du salon Agritechnica \u00e0 Hanovre en novembre 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au c\u0153ur du succ\u00e8s de l\u2019entreprise se trouve sa technologie brevet\u00e9e Plant-by-Plant AI, capable d\u2019identifier et de traiter chaque plante individuellement avec une empreinte de pulv\u00e9risation de quelques centim\u00e8tres seulement. Cette approche permet de r\u00e9duire l\u2019utilisation de pesticides et de produits phytosanitaires jusqu\u2019\u00e0 95%, tout en maintenant une efficacit\u00e9 compl\u00e8te du traitement. Elle offre aux agriculteurs la possibilit\u00e9 d\u2019utiliser en toute s\u00e9curit\u00e9 des produits non s\u00e9lectifs, de r\u00e9duire leurs co\u00fbts d\u2019intrants, de r\u00e9pondre \u00e0 des r\u00e9glementations plus strictes et d\u2019am\u00e9liorer les rendements, une avanc\u00e9e majeure vers une agriculture durable et pilot\u00e9e par les donn\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le financement de S\u00e9rie D a \u00e9t\u00e9 men\u00e9 par <a href=\"https:\/\/www.highlandeurope.com\/\">Highland Europe<\/a>, avec la participation de nouveaux investisseurs, dont <a href=\"https:\/\/www.ecbf.vc\/\">ECBF<\/a> et McWin Capital Partners (via le <a href=\"https:\/\/mcwin.fund\/ftf\/\">McWin Food Tech Fund<\/a>). Ce nouvel apport de capitaux fait suite \u00e0 une lev\u00e9e de fonds de USD 52 millions en 2023, co-men\u00e9e par <a href=\"https:\/\/www.aqton.eu\/\">AQTON SE<\/a> et <a href=\"https:\/\/www.cibusfund.com\/\">Cibus Capital<\/a>, confirmant la solidit\u00e9 financi\u00e8re et la cr\u00e9dibilit\u00e9 d\u2019Ecorobotix aupr\u00e8s des investisseurs.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Faire progresser encore la pr\u00e9cision agricole<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Ces nouveaux investissements nous permettent d\u2019acc\u00e9l\u00e9rer l\u2019innovation, d\u2019\u00e9largir notre champ d\u2019application \u00e0 de nouvelles cultures et de commercialiser plus rapidement nos algorithmes avanc\u00e9s \u00bb, a d\u00e9clar\u00e9 Dominique M\u00e9gret, CEO d\u2019Ecorobotix. \u00ab Nous d\u00e9ployons une solution \u00e9prouv\u00e9e pour offrir une alimentation de meilleure qualit\u00e9 \u00e0 l\u2019\u00e9chelle mondiale. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors du salon Agritechnica 2025, Ecorobotix d\u00e9voilera une nouvelle g\u00e9n\u00e9ration de sa technologie ARA, repoussant encore les limites de la pr\u00e9cision agricole. \u00ab Les agriculteurs sont confront\u00e9s \u00e0 la hausse des co\u00fbts, \u00e0 la p\u00e9nurie de main-d\u2019\u0153uvre et \u00e0 la pression de produire davantage avec moins d\u2019intrants. Notre nouvelle innovation les aide \u00e0 relever ces d\u00e9fis \u00bb, a ajout\u00e9 M\u00e9gret.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9sente dans plus de 20 pays en Europe, en Am\u00e9rique et en Oc\u00e9anie, Ecorobotix continue de red\u00e9finir la protection durable des cultures gr\u00e2ce \u00e0 l\u2019intelligence artificielle et \u00e0 l\u2019excellence de l\u2019ing\u00e9nierie en Suisse occidentale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant et pr\u00e9senter une nouvelle innovation \u00e0 Agritechnica.<\/p>\n","protected":false},"author":6,"featured_media":35924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[845],"tags":[1165,1179,1148,1145,1142,1161],"class_list":["post-35927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech","tag-agritech-fr-2","tag-artificial-intelligence-fr-2","tag-financing-fr-2","tag-foodtech-fr-2","tag-rd-fr-2","tag-robotics-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecorobotix l\u00e8ve USD 150 millions | GGBa<\/title>\n<meta name=\"description\" content=\"Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant\u2122.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecorobotix l\u00e8ve USD 150 millions | GGBa\" \/>\n<meta property=\"og:description\" content=\"Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant\u2122.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\" \/>\n<meta property=\"og:site_name\" content=\"Greater Geneva Bern area\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T13:47:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T13:51:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1180\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre-Yves Oehrli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Yves Oehrli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\"},\"author\":{\"name\":\"Pierre-Yves Oehrli\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"headline\":\"Ecorobotix l\u00e8ve USD 150 millions pour acc\u00e9l\u00e9rer l\u2019agriculture de pr\u00e9cision aliment\u00e9e par l\u2019IA\",\"datePublished\":\"2025-10-13T13:47:09+00:00\",\"dateModified\":\"2025-10-13T13:51:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\"},\"wordCount\":453,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg\",\"keywords\":[\"Agritech\",\"Artificial Intelligence\",\"Financing\",\"FoodTech\",\"R&amp;D\",\"Robotics\"],\"articleSection\":[\"Tech\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\",\"url\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\",\"name\":\"Ecorobotix l\u00e8ve USD 150 millions | GGBa\",\"isPartOf\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg\",\"datePublished\":\"2025-10-13T13:47:09+00:00\",\"dateModified\":\"2025-10-13T13:51:27+00:00\",\"author\":{\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\"},\"description\":\"Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant\u2122.\",\"breadcrumb\":{\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage\",\"url\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg\",\"contentUrl\":\"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg\",\"width\":1180,\"height\":811,\"caption\":\"Le syst\u00e8me ARA d\u2019Ecorobotix combine intelligence artificielle et pulv\u00e9risation ultra-haute pr\u00e9cision pour traiter chaque plante individuellement. | \u00a9 Ecorobotix\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ggba.swiss\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecorobotix l\u00e8ve USD 150 millions pour acc\u00e9l\u00e9rer l\u2019agriculture de pr\u00e9cision aliment\u00e9e par l\u2019IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#website\",\"url\":\"https:\/\/staging.ggba.swiss\/en\/\",\"name\":\"Greater Geneva Bern area\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41\",\"name\":\"Pierre-Yves Oehrli\",\"url\":\"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecorobotix l\u00e8ve USD 150 millions | GGBa","description":"Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant\u2122.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/","og_locale":"fr_FR","og_type":"article","og_title":"Ecorobotix l\u00e8ve USD 150 millions | GGBa","og_description":"Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant\u2122.","og_url":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/","og_site_name":"Greater Geneva Bern area","article_published_time":"2025-10-13T13:47:09+00:00","article_modified_time":"2025-10-13T13:51:27+00:00","og_image":[{"width":1180,"height":811,"url":"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg","type":"image\/jpeg"}],"author":"Pierre-Yves Oehrli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre-Yves Oehrli","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#article","isPartOf":{"@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/"},"author":{"name":"Pierre-Yves Oehrli","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"headline":"Ecorobotix l\u00e8ve USD 150 millions pour acc\u00e9l\u00e9rer l\u2019agriculture de pr\u00e9cision aliment\u00e9e par l\u2019IA","datePublished":"2025-10-13T13:47:09+00:00","dateModified":"2025-10-13T13:51:27+00:00","mainEntityOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/"},"wordCount":453,"commentCount":0,"image":{"@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg","keywords":["Agritech","Artificial Intelligence","Financing","FoodTech","R&amp;D","Robotics"],"articleSection":["Tech"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/","url":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/","name":"Ecorobotix l\u00e8ve USD 150 millions | GGBa","isPartOf":{"@id":"https:\/\/staging.ggba.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage"},"image":{"@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage"},"thumbnailUrl":"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg","datePublished":"2025-10-13T13:47:09+00:00","dateModified":"2025-10-13T13:51:27+00:00","author":{"@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41"},"description":"Le pionnier de l\u2019agtech Ecorobotix s\u00e9curise USD 150 millions pour faire progresser sa technologie Plant-by-Plant\u2122.","breadcrumb":{"@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#primaryimage","url":"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg","contentUrl":"https:\/\/ggba.swiss\/app\/uploads\/2025\/10\/EcoRobotix-ARA-1180x811-1.jpeg","width":1180,"height":811,"caption":"Le syst\u00e8me ARA d\u2019Ecorobotix combine intelligence artificielle et pulv\u00e9risation ultra-haute pr\u00e9cision pour traiter chaque plante individuellement. | \u00a9 Ecorobotix"},{"@type":"BreadcrumbList","@id":"https:\/\/ggba.swiss\/fr\/ecorobotix-leve-usd-150-millions-pour-accelerer-lagriculture-de-precision-alimentee-par-lia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ggba.swiss\/fr\/"},{"@type":"ListItem","position":2,"name":"Ecorobotix l\u00e8ve USD 150 millions pour acc\u00e9l\u00e9rer l\u2019agriculture de pr\u00e9cision aliment\u00e9e par l\u2019IA"}]},{"@type":"WebSite","@id":"https:\/\/staging.ggba.swiss\/en\/#website","url":"https:\/\/staging.ggba.swiss\/en\/","name":"Greater Geneva Bern area","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.ggba.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/staging.ggba.swiss\/en\/#\/schema\/person\/0b2e6d04131e3d01237dcb741fa33d41","name":"Pierre-Yves Oehrli","url":"https:\/\/ggba.swiss\/fr\/author\/pierre-yves-oehrli\/"}]}},"_links":{"self":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/35927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/comments?post=35927"}],"version-history":[{"count":3,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/35927\/revisions"}],"predecessor-version":[{"id":35933,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/posts\/35927\/revisions\/35933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media\/35924"}],"wp:attachment":[{"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/media?parent=35927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/categories?post=35927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ggba.swiss\/fr\/wp-json\/wp\/v2\/tags?post=35927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}